{"id":12425,"date":"2021-09-30T10:47:37","date_gmt":"2021-09-30T08:47:37","guid":{"rendered":"https:\/\/helena.hostko-gostovanje.si\/ika\/izdelek\/sifon-liv-za-pisoar\/"},"modified":"2022-07-11T12:38:12","modified_gmt":"2022-07-11T10:38:12","slug":"sifon-liv-za-pisoar","status":"publish","type":"product","link":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/","title":{"rendered":"Sifon LIV za pisoar"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;6px||3px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.13.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;38px&#8221; custom_margin=&#8221;||7px|||&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>SIFONI<\/h1>\n<p>[\/et_pb_text][et_pb_wc_breadcrumb breadcrumb_home_text=&#8221;Domov&#8221; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; body_text_color=&#8221;#000000&#8243; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_breadcrumb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;||1px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_images _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_title _builder_version=&#8221;4.13.1&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#DA251D&#8221; header_font_size=&#8221;20px&#8221; custom_margin=&#8221;||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_title][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_wc_additional_info show_title=&#8221;off&#8221; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; attribute_font=&#8221;|600|||||||&#8221; attribute_text_color=&#8221;#000000&#8243; custom_margin=&#8221;||26px|||&#8221; border_color_all=&#8221;#FFFFFF&#8221; border_style_all=&#8221;none&#8221; border_style_left=&#8221;none&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_additional_info][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0%||0%||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.10.8&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/liv.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2905 alignnone size-full\" src=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/liv.png\" alt=\"\" width=\"120\" height=\"50\"><\/a><\/p>\n<p>[\/et_pb_text][et_pb_wc_description _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; custom_margin=&#8221;||21px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_wc_price _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;20px&#8221; custom_margin=&#8221;-7px||23px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_price][et_pb_button button_url=&#8221;#izdelek_ponudba&#8221; button_text=&#8221;Po\u0161lji povpra\u0161evanje&#8221; module_class=&#8221;gumb-poslji-povprasevanje&#8221; _builder_version=&#8221;4.10.7&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_font=&#8221;|300|||||||&#8221; custom_margin=&#8221;||15px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;tel:0038645184444&#8243; button_text=&#8221;Pokli\u010di za ponudbo&#8221; disabled_on=&#8221;off|on|on&#8221; module_class=&#8221;gumb-poklici-za-ponudbo&#8221; _builder_version=&#8221;4.10.7&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_font=&#8221;|300|||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.10.8&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;11px||7px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;||||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;22px&#8221; custom_margin=&#8221;||11px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dokumenti za prenos<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; custom_padding=&#8221;10px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Datoteka produkta&#8221; image=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2021\/07\/pdf.png&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;164%&#8221; _builder_version=&#8221;4.13.0&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#DA251D&#8221; header_font_size=&#8221;14px&#8221; body_font=&#8221;|300|||||||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Katalog<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_5&#8243; _builder_version=&#8221;4.9.11&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;0px||12px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.13.1&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|300|||||||&#8221; header_2_text_color=&#8221;#DA251D&#8221; custom_margin=&#8221;||11px|||&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Opis<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;31%&#8221; custom_margin=&#8221;||8px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_wc_description description_type=&#8221;description&#8221; _builder_version=&#8221;4.9.10&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_button button_text=&#8221;Naslov posnetka&#8221; button_alignment=&#8221;left&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.13.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#EAEAEA&#8221; button_border_width=&#8221;0px&#8221; button_icon=&#8221;&#xe024;||divi||400&#8243; button_icon_color=&#8221;#DA251D&#8221; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; custom_padding=&#8221;1%|2%|1%|3%|true|false&#8221; custom_padding_tablet=&#8221;2%||2%|8%|true|false&#8221; custom_padding_phone=&#8221;4%||4%|13%|true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#C4C4C4&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#000000&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.10.8&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;0px|||||&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;90%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><span style=\"color: #da251d;\">|<\/span>Dodatna oprema<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;90%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Popup &#8211; #izdelek_ponudba&#8221; module_id=&#8221;izdelek_ponudba&#8221; module_class=&#8221;popup&#8221; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;50%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;3px||0px|||&#8221; da_is_popup=&#8221;on&#8221; da_popup_slug=&#8221;izdelek_ponudba&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;Helena Humar|Helena Humar-0&#8243; email=&#8221;info@ika.si, ema.gartnar@ika.si&#8221; title=&#8221;Sifon LIV za pisoar&#8221; success_message=&#8221;Zahvaljujemo se vam za poslano spro\u010dilo. Odgovorili vam bomo v najkraj\u0161em mo\u017enem \u010dasu.&#8221; submit_button_text=&#8221;Po\u0161lji&#8221; _builder_version=&#8221;4.13.1&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;53d44dc2-30db-41e5-95fe-dcad45dbd4d4&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_font=&#8221;|300|||||||&#8221; custom_button=&#8221;on&#8221; button_font=&#8221;|300|||||||&#8221; button_use_icon=&#8221;off&#8221; button_custom_padding=&#8221;|40px||40px|false|true&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; hover_enabled=&#8221;0&#8243; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#C4C4C4&#8243; global_colors_info=&#8221;{}&#8221; custom_message=&#8221;Podjetje: %%podjetje%%||et_pb_line_break_holder||Elektronski naslov: %%Email%%||et_pb_line_break_holder||Telefon: %%telefon%%||et_pb_line_break_holder||Opis: %%sporocilo%%&#8221; sticky_enabled=&#8221;0&#8243;][et_pb_contact_field field_id=&#8221;podjetje&#8221; field_title=&#8221;Podjetje&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.10.3&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Elektronski naslov&#8221; field_type=&#8221;email&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.10.3&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;telefon&#8221; field_title=&#8221;Telefon&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.10.3&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;sporocilo&#8221; field_title=&#8221;Sporo\u010dilo&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.10.3&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;gdpr&#8221; field_title=&#8221;Osebni podatki&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Strinjam se z uporabo osebnih podatkov.%22,%22checked%22:0,%22dragID%22:-1}%93&#8243; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.9.9&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sifon za pisoar, navpi\u010dni priklop.<\/p>\n<h2><\/h2>\n","protected":false},"featured_media":6045,"template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"A000605\n<h6>Sifon LIV za pisoar<\/h6>\n\u00a0\n\n<strong>Lastnosti:<\/strong>\n<ul>\n \t<li>Navpi\u010dna priklju\u010ditev pisoarja<\/li>\n \t<li>Sifon, izdelan iz materiala PP<\/li>\n \t<li>Prilo\u017eeno tesnilo<\/li>\n<\/ul>\n<h4><\/h4>\n<strong>Tehni\u010dni podatki:<\/strong>\n<ul>\n \t<li>Odto\u010dna cev: \u00d8 40 mm<\/li>\n<\/ul>\n\u00a0\n\n<strong>Skica:<\/strong>\n\n<a href=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-r.gif\"><img class=\"alignnone wp-image-6044\" src=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-r.gif\" alt=\"\" width=\"500\" height=\"500\"><\/a>","_et_gb_content_width":""},"product_brand":[],"product_cat":[331,447,450],"product_tag":[],"class_list":["post-12425","product","type-product","status-publish","has-post-thumbnail","product_cat-installation-material","product_cat-sewage-systems","product_cat-siphons-and-traps","pa_proizvajalec-liv-en","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sifon LIV za pisoar - Ika d.o.o.<\/title>\n<meta name=\"description\" content=\"Sifon za pisoar, navpi\u010dni priklop.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sifon LIV za pisoar - Ika d.o.o.\" \/>\n<meta property=\"og:description\" content=\"Sifon za pisoar, navpi\u010dni priklop.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/\" \/>\n<meta property=\"og:site_name\" content=\"Ika d.o.o.\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-11T10:38:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-s.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/\",\"url\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/\",\"name\":\"Sifon LIV za pisoar - Ika d.o.o.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ika.si\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/196030-s.jpg\",\"datePublished\":\"2021-09-30T08:47:37+00:00\",\"dateModified\":\"2022-07-11T10:38:12+00:00\",\"description\":\"Sifon za pisoar, navpi\u010dni priklop.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ika.si\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/196030-s.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ika.si\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/196030-s.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/sifon-liv-za-pisoar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ika.si\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.ika.si\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sifon LIV za pisoar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/#website\",\"url\":\"https:\\\/\\\/www.ika.si\\\/\",\"name\":\"Ika d.o.o.\",\"description\":\"Trgovsko podjetje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ika.si\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sifon LIV za pisoar - Ika d.o.o.","description":"Sifon za pisoar, navpi\u010dni priklop.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/","og_locale":"en_US","og_type":"article","og_title":"Sifon LIV za pisoar - Ika d.o.o.","og_description":"Sifon za pisoar, navpi\u010dni priklop.","og_url":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/","og_site_name":"Ika d.o.o.","article_modified_time":"2022-07-11T10:38:12+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-s.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/","url":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/","name":"Sifon LIV za pisoar - Ika d.o.o.","isPartOf":{"@id":"https:\/\/www.ika.si\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/#primaryimage"},"image":{"@id":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-s.jpg","datePublished":"2021-09-30T08:47:37+00:00","dateModified":"2022-07-11T10:38:12+00:00","description":"Sifon za pisoar, navpi\u010dni priklop.","breadcrumb":{"@id":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/#primaryimage","url":"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-s.jpg","contentUrl":"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/09\/196030-s.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.ika.si\/en\/izdelek\/sifon-liv-za-pisoar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ika.si\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.ika.si\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Sifon LIV za pisoar"}]},{"@type":"WebSite","@id":"https:\/\/www.ika.si\/#website","url":"https:\/\/www.ika.si\/","name":"Ika d.o.o.","description":"Trgovsko podjetje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ika.si\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product\/12425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/media\/6045"}],"wp:attachment":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/media?parent=12425"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product_brand?post=12425"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product_cat?post=12425"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product_tag?post=12425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}