{"id":18188,"date":"2023-03-15T12:41:49","date_gmt":"2023-03-15T11:41:49","guid":{"rendered":"https:\/\/www.ika.si\/?post_type=product&#038;p=18188"},"modified":"2026-07-13T10:35:44","modified_gmt":"2026-07-13T08:35:44","slug":"tipka-grohe-rapid-za-pisoar-tipka-skate-krom","status":"publish","type":"product","link":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/","title":{"rendered":"Tipka GROHE RAPID za pisoar &#8211; tipka skate, krom"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;6px||3px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;||||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;38px&#8221; custom_margin=&#8221;||7px|||&#8221; header_font_size_tablet=&#8221;30px&#8221; header_font_size_phone=&#8221;25px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>AKTIVIRNE TIPKE ZA PISOAR<\/h1>\n<p>[\/et_pb_text][et_pb_wc_breadcrumb breadcrumb_home_text=&#8221;Domov&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; body_text_color=&#8221;#000000&#8243; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_breadcrumb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;||1px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_images _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_images][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;3%||||false|false&#8221; custom_padding_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_wc_title _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_font=&#8221;||||||||&#8221; header_text_color=&#8221;#DA251D&#8221; header_font_size=&#8221;20px&#8221; custom_margin=&#8221;||30px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_title][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_wc_additional_info show_title=&#8221;off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; attribute_font=&#8221;|600|||||||&#8221; attribute_text_color=&#8221;#000000&#8243; custom_margin=&#8221;||26px|||&#8221; border_color_all=&#8221;#FFFFFF&#8221; border_style_all=&#8221;none&#8221; border_style_left=&#8221;none&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_additional_info][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;70%&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;0%||0%||true|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><a href=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/10\/grohe.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2986\" src=\"https:\/\/www.ika.si\/wp-content\/uploads\/2021\/10\/grohe.png\" alt=\"\" width=\"107\" height=\"80\"><\/a><\/p>\n<p>[\/et_pb_text][et_pb_wc_description _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; custom_margin=&#8221;||21px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_wc_price _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; body_font_size=&#8221;20px&#8221; custom_margin=&#8221;-7px||23px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_price][et_pb_button button_url=&#8221;#izdelek_ponudba&#8221; button_text=&#8221;Po\u0161lji povpra\u0161evanje&#8221; module_class=&#8221;gumb-poslji-povprasevanje&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_font=&#8221;|300|||||||&#8221; custom_margin=&#8221;||15px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;tel:0038645184444&#8243; button_text=&#8221;Pokli\u010di za ponudbo&#8221; disabled_on=&#8221;off|on|on&#8221; module_class=&#8221;gumb-poklici-za-ponudbo&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_font=&#8221;|300|||||||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;11px||7px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;||||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;22px&#8221; custom_margin=&#8221;||11px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Dokumenti za prenos<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_6,1_6,1_6,1_6,1_6,1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; custom_padding=&#8221;10px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;GROHE &#8221; image=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2021\/07\/pdf.png&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;164%&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.7&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#DA251D&#8221; header_font_size=&#8221;14px&#8221; body_font=&#8221;|300|||||||&#8221; link_option_url=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2026\/07\/GroheCatalogueMediterraneanPro2026_1.pdf&#8221; link_option_url_new_window=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>Katalog<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.27.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;GROHE barvne razli\u010dice&#8221; image=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2021\/07\/pdf.png&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;164%&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#DA251D&#8221; header_font_size=&#8221;14px&#8221; body_font=&#8221;|300|||||||&#8221; link_option_url=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2025\/11\/letak-barve-zaloga-8-tednov_compressed.pdf&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Katalog<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;GROHE mat \u010drna&#8221; image=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2021\/07\/pdf.png&#8221; icon_placement=&#8221;left&#8221; content_max_width=&#8221;164%&#8221; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; header_text_color=&#8221;#DA251D&#8221; header_font_size=&#8221;14px&#8221; body_font=&#8221;|300|||||||&#8221; link_option_url=&#8221;https:\/\/www.ika.si\/wp-content\/uploads\/2025\/11\/GROHE-Matte-Black_compressed.pdf&#8221; link_option_url_new_window=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Katalog<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_6&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;0px||12px|||&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|300|||||||&#8221; header_2_text_color=&#8221;#DA251D&#8221; custom_margin=&#8221;||11px|||&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Opis<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;31%&#8221; custom_margin=&#8221;||8px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_wc_description description_type=&#8221;description&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; body_font=&#8221;||||||||&#8221; body_text_color=&#8221;#000000&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_description][et_pb_button button_text=&#8221;Naslov posnetka&#8221; button_alignment=&#8221;left&#8221; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;17px&#8221; button_text_color=&#8221;#000000&#8243; button_bg_color=&#8221;#EAEAEA&#8221; button_border_width=&#8221;0px&#8221; button_icon=&#8221;&#xe024;||divi||400&#8243; button_icon_color=&#8221;#DA251D&#8221; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; custom_padding=&#8221;1%|2%|1%|3%|true|false&#8221; custom_padding_tablet=&#8221;2%||2%|8%|true|false&#8221; custom_padding_phone=&#8221;4%||4%|13%|true|false&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#C4C4C4&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#000000&#8243;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; custom_padding=&#8221;0px|||||&#8221; da_disable_devices=&#8221;off|off|off&#8221; disabled=&#8221;on&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;90%&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|300|||||||&#8221; header_2_text_color=&#8221;#DA251D&#8221; custom_margin=&#8221;||11px|||&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; header_2_font_size__hover_enabled=&#8221;on|desktop&#8221;]<\/p>\n<h2>Dodatna oprema<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;31%&#8221; custom_margin=&#8221;||8px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;90%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#EAEAEA&#8221; custom_padding=&#8221;4%|2%|4%|2%|true|true&#8221; border_radii=&#8221;on|20px|20px|20px|20px&#8221; global_colors_info=&#8221;{}&#8221; background__hover_enabled=&#8221;on|hover&#8221; background_color__hover=&#8221;#DA251D&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;25px&#8221; global_colors_info=&#8221;{}&#8221; header_text_color__hover_enabled=&#8221;on|hover&#8221; header_text_color__hover=&#8221;#FFFFFF&#8221;]<\/p>\n<h1>Ime kategorije<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;90%&#8221; module_alignment=&#8221;center&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_module=&#8221;4472&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; da_is_popup=&#8221;off&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; width=&#8221;90%&#8221; max_width=&#8221;96%&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text disabled_on=&#8221;off|off|off&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; header_2_font=&#8221;|300|||||||&#8221; header_2_text_color=&#8221;#DA251D&#8221; custom_margin=&#8221;||11px|||&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;&#8221; header_2_font_size_phone=&#8221;23px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; header_2_line_height_tablet=&#8221;&#8221; header_2_line_height_phone=&#8221;1.2em&#8221; header_2_line_height_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>Mogo\u010de vas zanima tudi<\/h2>\n<p>[\/et_pb_text][et_pb_divider color=&#8221;#C4C4C4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;45%&#8221; max_width_tablet=&#8221;97%&#8221; max_width_phone=&#8221;&#8221; max_width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;||8px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_wc_upsells _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; title_font=&#8221;||||||||&#8221; title_text_align=&#8221;left&#8221; title_text_color=&#8221;#DA251D&#8221; product_title_font=&#8221;||||||||&#8221; product_title_text_align=&#8221;center&#8221; product_title_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_wc_upsells][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Popup &#8211; #izdelek_ponudba&#8221; module_id=&#8221;izdelek_ponudba&#8221; module_class=&#8221;popup&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;50%&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;&#8221; width_last_edited=&#8221;on|phone&#8221; custom_padding=&#8221;3px||0px|||&#8221; da_is_popup=&#8221;on&#8221; da_popup_slug=&#8221;izdelek_ponudba&#8221; da_disable_devices=&#8221;off|off|off&#8221; global_colors_info=&#8221;{}&#8221; da_exit_intent=&#8221;off&#8221; da_has_close=&#8221;on&#8221; da_alt_close=&#8221;off&#8221; da_dark_close=&#8221;off&#8221; da_not_modal=&#8221;on&#8221; da_is_singular=&#8221;off&#8221; da_with_loader=&#8221;off&#8221; da_has_shadow=&#8221;on&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;100%&#8221; max_width=&#8221;100%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;Helena Humar|Helena Humar-0&#8243; email=&#8221;info@ika.si, ema.gartnar@ika.si&#8221; title=&#8221;Tipka GROHE RAPID za pisoar &#8211; tipka skate, krom&#8221; custom_message=&#8221;Podjetje: %%podjetje%%||et_pb_line_break_holder||Elektronski naslov: %%Email%%||et_pb_line_break_holder||Telefon: %%telefon%%||et_pb_line_break_holder||Opis: %%sporocilo%%&#8221; success_message=&#8221;Zahvaljujemo se vam za poslano spro\u010dilo. Odgovorili vam bomo v najkraj\u0161em mo\u017enem \u010dasu. &#8221; submit_button_text=&#8221;Po\u0161lji&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;1d9a28b8-8d3d-4ac0-b1ca-1c055515317e&#8221; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_font=&#8221;|300|||||||&#8221; custom_button=&#8221;on&#8221; button_font=&#8221;|300|||||||&#8221; button_use_icon=&#8221;off&#8221; button_custom_padding=&#8221;|40px||40px|false|true&#8221; max_width=&#8221;80%&#8221; module_alignment=&#8221;center&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#C4C4C4&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_contact_field field_id=&#8221;podjetje&#8221; field_title=&#8221;Podjetje&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;Elektronski naslov&#8221; field_type=&#8221;email&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;telefon&#8221; field_title=&#8221;Telefon&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;sporocilo&#8221; field_title=&#8221;Sporo\u010dilo&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;gdpr&#8221; field_title=&#8221;Osebni podatki&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Strinjam se z uporabo osebnih podatkov.%22,%22checked%22:0,%22dragID%22:-1}%93&#8243; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mehanske splakovalne tipke za pisoar.<\/p>\n","protected":false},"featured_media":18191,"template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<h6><strong>Tipka GROHE RAPID za pisoar - tipka skate, krom<\/strong><\/h6>\n(A074607)\n\n<a href=\"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/1409035-e1678879461302.jpg\"><img class=\"alignnone wp-image-18181\" src=\"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/1409035-e1678879461302.jpg\" alt=\"\" width=\"500\" height=\"600\"><\/a>","_et_gb_content_width":""},"product_brand":[],"product_cat":[502,532,534],"product_tag":[],"class_list":["post-18188","product","type-product","status-publish","has-post-thumbnail","product_cat-bathrooms","product_cat-toilet-cisterns","product_cat-urinal-flushing","pa_proizvajalec-grohe-en","first","instock","shipping-taxable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tipka GROHE RAPID za pisoar - tipka skate, krom - Ika d.o.o.<\/title>\n<meta name=\"description\" content=\"Mehanske splakovalne tipke za pisoar. Tipka 38784000 GROHE RAPID za pisoar - tipka skate, krom.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tipka GROHE RAPID za pisoar - tipka skate, krom - Ika d.o.o.\" \/>\n<meta property=\"og:description\" content=\"Mehanske splakovalne tipke za pisoar. Tipka 38784000 GROHE RAPID za pisoar - tipka skate, krom.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/\" \/>\n<meta property=\"og:site_name\" content=\"Ika d.o.o.\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T08:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/38784000_1_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/\",\"url\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/\",\"name\":\"Tipka GROHE RAPID za pisoar - tipka skate, krom - Ika d.o.o.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ika.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/38784000_1_1.jpg\",\"datePublished\":\"2023-03-15T11:41:49+00:00\",\"dateModified\":\"2026-07-13T08:35:44+00:00\",\"description\":\"Mehanske splakovalne tipke za pisoar. Tipka 38784000 GROHE RAPID za pisoar - tipka skate, krom.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ika.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/38784000_1_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ika.si\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/38784000_1_1.jpg\",\"width\":480,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/en\\\/izdelek\\\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ika.si\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.ika.si\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tipka GROHE RAPID za pisoar &#8211; tipka skate, krom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ika.si\\\/#website\",\"url\":\"https:\\\/\\\/www.ika.si\\\/\",\"name\":\"Ika d.o.o.\",\"description\":\"Trgovsko podjetje\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ika.si\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipka GROHE RAPID za pisoar - tipka skate, krom - Ika d.o.o.","description":"Mehanske splakovalne tipke za pisoar. Tipka 38784000 GROHE RAPID za pisoar - tipka skate, krom.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/","og_locale":"en_US","og_type":"article","og_title":"Tipka GROHE RAPID za pisoar - tipka skate, krom - Ika d.o.o.","og_description":"Mehanske splakovalne tipke za pisoar. Tipka 38784000 GROHE RAPID za pisoar - tipka skate, krom.","og_url":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/","og_site_name":"Ika d.o.o.","article_modified_time":"2026-07-13T08:35:44+00:00","og_image":[{"width":480,"height":480,"url":"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/38784000_1_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/","url":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/","name":"Tipka GROHE RAPID za pisoar - tipka skate, krom - Ika d.o.o.","isPartOf":{"@id":"https:\/\/www.ika.si\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/#primaryimage"},"image":{"@id":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/38784000_1_1.jpg","datePublished":"2023-03-15T11:41:49+00:00","dateModified":"2026-07-13T08:35:44+00:00","description":"Mehanske splakovalne tipke za pisoar. Tipka 38784000 GROHE RAPID za pisoar - tipka skate, krom.","breadcrumb":{"@id":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/#primaryimage","url":"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/38784000_1_1.jpg","contentUrl":"https:\/\/www.ika.si\/wp-content\/uploads\/2023\/03\/38784000_1_1.jpg","width":480,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.ika.si\/en\/izdelek\/tipka-grohe-rapid-za-pisoar-tipka-skate-krom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ika.si\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.ika.si\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Tipka GROHE RAPID za pisoar &#8211; tipka skate, krom"}]},{"@type":"WebSite","@id":"https:\/\/www.ika.si\/#website","url":"https:\/\/www.ika.si\/","name":"Ika d.o.o.","description":"Trgovsko podjetje","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ika.si\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product\/18188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/media\/18191"}],"wp:attachment":[{"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/media?parent=18188"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product_brand?post=18188"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product_cat?post=18188"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ika.si\/en\/wp-json\/wp\/v2\/product_tag?post=18188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}